{"id":4603,"date":"2021-07-22T14:58:43","date_gmt":"2021-07-22T12:58:43","guid":{"rendered":"http:\/\/fvviszx.cluster027.hosting.ovh.net\/2023\/?post_type=tribe_events&#038;p=4603"},"modified":"2022-01-20T15:21:22","modified_gmt":"2022-01-20T14:21:22","slug":"co-creatiesessie-individuele-belevingen-leiestreek","status":"publish","type":"tribe_events","link":"https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/","title":{"rendered":"Co-creatiesessie individuele belevingen Leiestreek"},"content":{"rendered":"<h2>Doelstelling<\/h2>\n<p>Het ontwikkelen van een individuele beleving in jouw onderneming. Via co-creatie met andere deelnemers kom je op de beste concepten en kun je jouw beleving een extra dimensie geven.<\/p>\n<hr \/>\n<h2><strong>Doelgroep<\/strong><\/h2>\n<p>Toeristische ondernemers die willen inzetten op meer beleving in hun zaak.<\/p>\n<hr \/>\n<h2><strong>Vereisten<\/strong><\/h2>\n<p>Geen enkele! Goesting, nieuwsgierigheid, open mind en creativiteit.<\/p>\n<hr \/>\n<h2><strong>Inhoud van de workshop<\/strong><\/h2>\n<p>We werken verder op de idee\u00ebn van de inspiratiesessie in september en gaan via verschillende rondes werken naar concrete nieuwe belevingsconcepten voor jouw zaak.<\/p>\n<hr \/>\n<h2><strong>Lesgevers<\/strong><\/h2>\n<h3>Studio XD<\/h3>\n<p>Als experten in het ontwikkelen van belevingsconcepten, nemen ze ons mee in de wereld van Design thinking en Experience Design. Wat is een goeie beleving en hoe is die opgebouwd? Ze inspireren, geven ons tips, begeleiden ons denkproces, fungeren als klankbord en helpen bij het ontwikkelen van onze concepten.<\/p>\n<h3>Michel Groenenstijn<\/h3>\n<p>Al ruim vijftien jaar ondernemer. Altijd op zoek naar hoe dingen anders, beter, leuker kunnen. Na de verkoop van zijn reisorganisatie gestart met het ontwerpen en bouwen van experiences. Michel is vaak de initiator en verbinder in een project. Naast Studio XD co-founder van Goya Experiences en Hotel Wonderland.<\/p>\n<h3>Raymond Klompsma<\/h3>\n<p>Raymond is een gepassioneerd ervaringsdeskundige. Oprichter van srprs.me, co-founder van Goya Experiences en werkt momenteel als founder aan Hotel Wonderland. Creatief brein en expert op het vlak van PR en marketing.<\/p>\n<hr \/>\n<h2><strong>Belangrijk om te weten<\/strong><\/h2>\n<p>Het begeleidingstraject omvat een co-creatiesessie, individuele coaching en klankborden met experten. Je wordt individueel begeleid door een belevingsexpert om je concept vorm te geven en te helpen uitvoeren.<\/p>\n<p>Beperkt aantal deelnemers.<\/p>\n<p><a href=\"https:\/\/forms.gle\/3FPE5eumLqpTwMbr5\" target=\"_blank\" rel=\"noopener\"><span class=\"custom-button\">Inschrijven<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Het ontwikkelen van een individuele beleving in jouw onderneming.<\/p>\n","protected":false},"author":17,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[359,591],"class_list":["post-4603","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-opleiding","tribe_events_cat-past-nl","cat_opleiding","cat_past-nl"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Co-creatiesessie individuele belevingen Leiestreek - TourismLab<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Co-creatiesessie individuele belevingen Leiestreek - TourismLab\" \/>\n<meta property=\"og:description\" content=\"Het ontwikkelen van een individuele beleving in jouw onderneming.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/\" \/>\n<meta property=\"og:site_name\" content=\"TourismLab\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-20T14:21:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tourismlab.eu\/2023\/wp-content\/uploads\/2020\/08\/fav-tourismlab-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/evenement\\\/co-creatiesessie-individuele-belevingen-leiestreek\\\/\",\"url\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/evenement\\\/co-creatiesessie-individuele-belevingen-leiestreek\\\/\",\"name\":\"Co-creatiesessie individuele belevingen Leiestreek - TourismLab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/#website\"},\"datePublished\":\"2021-07-22T12:58:43+00:00\",\"dateModified\":\"2022-01-20T14:21:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/evenement\\\/co-creatiesessie-individuele-belevingen-leiestreek\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/evenement\\\/co-creatiesessie-individuele-belevingen-leiestreek\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/evenement\\\/co-creatiesessie-individuele-belevingen-leiestreek\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Evenementen\",\"item\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Co-creatiesessie individuele belevingen Leiestreek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/\",\"name\":\"TourismLab\",\"description\":\"Tourisme Transfrontalier : exp\u00e9rimentations et innovations\",\"publisher\":{\"@id\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/#organization\",\"name\":\"Tourism Lab\",\"url\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/fvviszx.cluster027.hosting.ovh.net\\\/2023\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Tourism-Lab-bloc-marque-cmyk.png\",\"contentUrl\":\"http:\\\/\\\/fvviszx.cluster027.hosting.ovh.net\\\/2023\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Tourism-Lab-bloc-marque-cmyk.png\",\"width\":834,\"height\":374,\"caption\":\"Tourism Lab\"},\"image\":{\"@id\":\"https:\\\/\\\/tourismlab.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Co-creatiesessie individuele belevingen Leiestreek - TourismLab","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/","og_locale":"nl_NL","og_type":"article","og_title":"Co-creatiesessie individuele belevingen Leiestreek - TourismLab","og_description":"Het ontwikkelen van een individuele beleving in jouw onderneming.","og_url":"https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/","og_site_name":"TourismLab","article_modified_time":"2022-01-20T14:21:22+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/tourismlab.eu\/2023\/wp-content\/uploads\/2020\/08\/fav-tourismlab-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/","url":"https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/","name":"Co-creatiesessie individuele belevingen Leiestreek - TourismLab","isPartOf":{"@id":"https:\/\/tourismlab.eu\/nl\/#website"},"datePublished":"2021-07-22T12:58:43+00:00","dateModified":"2022-01-20T14:21:22+00:00","breadcrumb":{"@id":"https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tourismlab.eu\/nl\/evenement\/co-creatiesessie-individuele-belevingen-leiestreek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Evenementen","item":"https:\/\/tourismlab.eu\/nl\/events\/"},{"@type":"ListItem","position":2,"name":"Co-creatiesessie individuele belevingen Leiestreek"}]},{"@type":"WebSite","@id":"https:\/\/tourismlab.eu\/nl\/#website","url":"https:\/\/tourismlab.eu\/nl\/","name":"TourismLab","description":"Tourisme Transfrontalier : exp\u00e9rimentations et innovations","publisher":{"@id":"https:\/\/tourismlab.eu\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tourismlab.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/tourismlab.eu\/nl\/#organization","name":"Tourism Lab","url":"https:\/\/tourismlab.eu\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/tourismlab.eu\/nl\/#\/schema\/logo\/image\/","url":"http:\/\/fvviszx.cluster027.hosting.ovh.net\/2023\/wp-content\/uploads\/2020\/03\/Tourism-Lab-bloc-marque-cmyk.png","contentUrl":"http:\/\/fvviszx.cluster027.hosting.ovh.net\/2023\/wp-content\/uploads\/2020\/03\/Tourism-Lab-bloc-marque-cmyk.png","width":834,"height":374,"caption":"Tourism Lab"},"image":{"@id":"https:\/\/tourismlab.eu\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tourismlab.eu\/nl\/wp-json\/wp\/v2\/tribe_events\/4603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tourismlab.eu\/nl\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/tourismlab.eu\/nl\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/tourismlab.eu\/nl\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":0,"href":"https:\/\/tourismlab.eu\/nl\/wp-json\/wp\/v2\/tribe_events\/4603\/revisions"}],"wp:attachment":[{"href":"https:\/\/tourismlab.eu\/nl\/wp-json\/wp\/v2\/media?parent=4603"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tourismlab.eu\/nl\/wp-json\/wp\/v2\/tags?post=4603"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/tourismlab.eu\/nl\/wp-json\/wp\/v2\/tribe_events_cat?post=4603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}